{"id":559,"count":1,"description":"","link":"https:\/\/www.argensend.com\/en\/tag\/futbol\/","name":"futbol","slug":"futbol","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.argensend.com\/en\/tag\/futbol\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/559\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.argensend.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/tag\\\/futbol\\\/#listItem\",\"name\":\"futbol\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/tag\\\/futbol\\\/#listItem\",\"position\":2,\"name\":\"futbol\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/559\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/559\\\/\",\"name\":\"futbol | Argen\\u2192Send\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/559\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/#organization\",\"name\":\"Argen\\u2192Send\",\"description\":\"Productos argentinos al mundo\",\"url\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/\",\"telephone\":\"+541123749692\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.argensend.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/argensend_Website_Logo_v3.png?fit=300%2C37&ssl=1\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/559\\\/#organizationLogo\",\"width\":300,\"height\":37},\"image\":{\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/559\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/argensend\",\"https:\\\/\\\/www.instagram.com\\\/argensend\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/\",\"name\":\"Argen\\u2192Send\",\"description\":\"Productos argentinos al mundo\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.argensend.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"futbol | Argen\u2192Send","description":"","canonical_url":"https:\/\/www.argensend.com\/en\/tag\/futbol\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.argensend.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.argensend.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.argensend.com\/en\/tag\/futbol\/#listItem","name":"futbol"}},{"@type":"ListItem","@id":"https:\/\/www.argensend.com\/en\/tag\/futbol\/#listItem","position":2,"name":"futbol","previousItem":{"@type":"ListItem","@id":"https:\/\/www.argensend.com\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559\/#collectionpage","url":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559\/","name":"futbol | Argen\u2192Send","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.argensend.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.argensend.com\/en\/#organization","name":"Argen\u2192Send","description":"Productos argentinos al mundo","url":"https:\/\/www.argensend.com\/en\/","telephone":"+541123749692","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.argensend.com\/wp-content\/uploads\/2022\/06\/argensend_Website_Logo_v3.png?fit=300%2C37&ssl=1","@id":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559\/#organizationLogo","width":300,"height":37},"image":{"@id":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/argensend","https:\/\/www.instagram.com\/argensend"]},{"@type":"WebSite","@id":"https:\/\/www.argensend.com\/en\/#website","url":"https:\/\/www.argensend.com\/en\/","name":"Argen\u2192Send","description":"Productos argentinos al mundo","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.argensend.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.argensend.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tfutbol\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.argensend.com\/en"},{"label":"futbol","link":"https:\/\/www.argensend.com\/en\/tag\/futbol\/"}],"_links":{"self":[{"href":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags\/559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.argensend.com\/en\/wp-json\/wp\/v2\/posts?tags=559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}